{"id":5922,"date":"2024-02-11T13:05:48","date_gmt":"2024-02-11T12:05:48","guid":{"rendered":"https:\/\/frenchpleinairpainters.com\/?post_type=tribe_events&#038;p=5922"},"modified":"2024-02-12T23:52:51","modified_gmt":"2024-02-12T22:52:51","slug":"la-sortie-du-mois-de-fevrier-2024","status":"publish","type":"tribe_events","link":"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/","title":{"rendered":"La sortie du mois de f\u00e9vrier 2024"},"content":{"rendered":"<p><a href=\"https:\/\/frenchpleinairpainters.com\/index.php\/2024\/02\/12\/sortie-le-17-fevrier-autour-du-salon-art-capital-paris\/\" target=\"_blank\" rel=\"noopener\">Sortie autour de l&rsquo;exposition Art Capital Samedi 17 f\u00e9vrier<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sortie autour de l&rsquo;exposition Art Capital Samedi 17 f\u00e9vrier<\/p>\n","protected":false},"author":7,"featured_media":5916,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[197],"tribe_events_cat":[],"class_list":["post-5922","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-french-plein-air-art"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La sortie du mois de f\u00e9vrier 2024 - French Plein Air Painters \u00a9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La sortie du mois de f\u00e9vrier 2024 - French Plein Air Painters \u00a9\" \/>\n<meta property=\"og:description\" content=\"Sortie autour de l&rsquo;exposition Art Capital Samedi 17 f\u00e9vrier\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"French Plein Air Painters \u00a9\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-12T22:52:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchpleinairpainters.com\/wp-content\/uploads\/2024\/02\/sortie-ArtCapital-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1174\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/index.php\\\/event\\\/la-sortie-du-mois-de-fevrier-2024\\\/\",\"url\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/index.php\\\/event\\\/la-sortie-du-mois-de-fevrier-2024\\\/\",\"name\":\"La sortie du mois de f\u00e9vrier 2024 - French Plein Air Painters \u00a9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/index.php\\\/event\\\/la-sortie-du-mois-de-fevrier-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/index.php\\\/event\\\/la-sortie-du-mois-de-fevrier-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/sortie-ArtCapital-scaled.jpg\",\"datePublished\":\"2024-02-11T12:05:48+00:00\",\"dateModified\":\"2024-02-12T22:52:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/index.php\\\/event\\\/la-sortie-du-mois-de-fevrier-2024\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frenchpleinairpainters.com\\\/index.php\\\/event\\\/la-sortie-du-mois-de-fevrier-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/index.php\\\/event\\\/la-sortie-du-mois-de-fevrier-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/sortie-ArtCapital-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/sortie-ArtCapital-scaled.jpg\",\"width\":2560,\"height\":1174},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/index.php\\\/event\\\/la-sortie-du-mois-de-fevrier-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/index.php\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/index.php\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La sortie du mois de f\u00e9vrier 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/#website\",\"url\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/\",\"name\":\"French Plein Air Painters \u00a9\",\"description\":\"En France nombreux artistes peignent en plein air d\u2019apr\u00e8s la tradition artistique qui remonte m\u00eame au del\u00e0 des Impressionnistes.\",\"publisher\":{\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/#organization\",\"name\":\"Association Festival Cultures Crois\u00e9es \u2013 AFCC\",\"url\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/AFCC_logo2008_BLANCJPG.jpg\",\"contentUrl\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/AFCC_logo2008_BLANCJPG.jpg\",\"width\":654,\"height\":741,\"caption\":\"Association Festival Cultures Crois\u00e9es \u2013 AFCC\"},\"image\":{\"@id\":\"https:\\\/\\\/frenchpleinairpainters.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La sortie du mois de f\u00e9vrier 2024 - French Plein Air Painters \u00a9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/","og_locale":"fr_FR","og_type":"article","og_title":"La sortie du mois de f\u00e9vrier 2024 - French Plein Air Painters \u00a9","og_description":"Sortie autour de l&rsquo;exposition Art Capital Samedi 17 f\u00e9vrier","og_url":"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/","og_site_name":"French Plein Air Painters \u00a9","article_modified_time":"2024-02-12T22:52:51+00:00","og_image":[{"width":2560,"height":1174,"url":"https:\/\/frenchpleinairpainters.com\/wp-content\/uploads\/2024\/02\/sortie-ArtCapital-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/","url":"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/","name":"La sortie du mois de f\u00e9vrier 2024 - French Plein Air Painters \u00a9","isPartOf":{"@id":"https:\/\/frenchpleinairpainters.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/#primaryimage"},"image":{"@id":"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchpleinairpainters.com\/wp-content\/uploads\/2024\/02\/sortie-ArtCapital-scaled.jpg","datePublished":"2024-02-11T12:05:48+00:00","dateModified":"2024-02-12T22:52:51+00:00","breadcrumb":{"@id":"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/#primaryimage","url":"https:\/\/frenchpleinairpainters.com\/wp-content\/uploads\/2024\/02\/sortie-ArtCapital-scaled.jpg","contentUrl":"https:\/\/frenchpleinairpainters.com\/wp-content\/uploads\/2024\/02\/sortie-ArtCapital-scaled.jpg","width":2560,"height":1174},{"@type":"BreadcrumbList","@id":"https:\/\/frenchpleinairpainters.com\/index.php\/event\/la-sortie-du-mois-de-fevrier-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/frenchpleinairpainters.com\/index.php\/en\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/frenchpleinairpainters.com\/index.php\/events\/"},{"@type":"ListItem","position":3,"name":"La sortie du mois de f\u00e9vrier 2024"}]},{"@type":"WebSite","@id":"https:\/\/frenchpleinairpainters.com\/#website","url":"https:\/\/frenchpleinairpainters.com\/","name":"French Plein Air Painters \u00a9","description":"En France nombreux artistes peignent en plein air d\u2019apr\u00e8s la tradition artistique qui remonte m\u00eame au del\u00e0 des Impressionnistes.","publisher":{"@id":"https:\/\/frenchpleinairpainters.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchpleinairpainters.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/frenchpleinairpainters.com\/#organization","name":"Association Festival Cultures Crois\u00e9es \u2013 AFCC","url":"https:\/\/frenchpleinairpainters.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchpleinairpainters.com\/#\/schema\/logo\/image\/","url":"https:\/\/frenchpleinairpainters.com\/wp-content\/uploads\/2019\/10\/AFCC_logo2008_BLANCJPG.jpg","contentUrl":"https:\/\/frenchpleinairpainters.com\/wp-content\/uploads\/2019\/10\/AFCC_logo2008_BLANCJPG.jpg","width":654,"height":741,"caption":"Association Festival Cultures Crois\u00e9es \u2013 AFCC"},"image":{"@id":"https:\/\/frenchpleinairpainters.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/frenchpleinairpainters.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/5922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchpleinairpainters.com\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/frenchpleinairpainters.com\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/frenchpleinairpainters.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":2,"href":"https:\/\/frenchpleinairpainters.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/5922\/revisions"}],"predecessor-version":[{"id":5925,"href":"https:\/\/frenchpleinairpainters.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/5922\/revisions\/5925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchpleinairpainters.com\/index.php\/wp-json\/wp\/v2\/media\/5916"}],"wp:attachment":[{"href":"https:\/\/frenchpleinairpainters.com\/index.php\/wp-json\/wp\/v2\/media?parent=5922"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchpleinairpainters.com\/index.php\/wp-json\/wp\/v2\/tags?post=5922"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/frenchpleinairpainters.com\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=5922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}